{"id":19348,"date":"2020-04-13T18:19:46","date_gmt":"2020-04-13T16:19:46","guid":{"rendered":"https:\/\/www.antderground.com\/producto\/formigueiro-anti-vazamento-areia\/"},"modified":"2020-04-13T18:19:46","modified_gmt":"2020-04-13T16:19:46","slug":"formigueiro-anti-vazamento-areia","status":"publish","type":"product","link":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/","title":{"rendered":"Formigueiro anti-vazamento (areia)"},"content":{"rendered":"<p>Formigueiro anti-vazamento (areia) com tampa vermelha inclu\u00edda.<\/p>\n<p>O formigueiro anti-vazamento com areia.<\/p>\n<p>Este formigueiro acr\u00edlico consiste em uma \u00fanica c\u00e2mara com areia e um sistema de umidade com esponjas localizadas em cada lado do formigueiro.<\/p>\n<p>Projetado para ser usado com 100% de areia de s\u00edlica, uma mistura de areia com argila (80\/20%) ou qualquer outro substrato compat\u00edvel.<\/p>\n<p>Esp\u00e9cies de micro e mini formigas que requerem um substrato e um alto n\u00edvel de umidade, como Solenopsis Fugax, formigas Lasius Flavus, entre outras&#8230;<\/p>\n<p>Possui caixa forrageira integrada, para poder alimentar as formigas reduzindo o risco de fuga e\/ou utiliz\u00e1-la com \u00f3leo mineral anti-vazamento.<\/p>\n<p>Sua loja de formigueiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Formigueiro anti-vazamento (areia) com tampa vermelha inclu\u00edda. O formigueiro anti-vazamento com areia. Este formigueiro acr\u00edlico consiste em uma \u00fanica c\u00e2mara<\/p>\n","protected":false},"featured_media":19362,"template":"","meta":[],"product_brand":[],"product_cat":[379,399],"product_tag":[],"class_list":{"0":"post-19348","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-formigueiros","7":"product_cat-formigueiros-para-especies-pequenas","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formigueiro anti-vazamento (areia) - ANTDERGROUND<\/title>\n<meta name=\"description\" content=\"Formigueiro anti-vazamento com areia. Formigueiro para formigas ex\u00f3ticas. Formigueiro de areia. loja de formigueiro acr\u00edlico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formigueiro anti-vazamento (areia) - ANTDERGROUND\" \/>\n<meta property=\"og:description\" content=\"Formigueiro anti-vazamento com areia. Formigueiro para formigas ex\u00f3ticas. Formigueiro de areia. loja de formigueiro acr\u00edlico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/\" \/>\n<meta property=\"og:site_name\" content=\"ANTDERGROUND\" \/>\n<meta property=\"og:image\" content=\"https:\/\/antderground.com\/wp-content\/uploads\/2020\/04\/antifugas-arena-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"591\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/\",\"url\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/\",\"name\":\"Formigueiro anti-vazamento (areia) - ANTDERGROUND\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/antderground.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/antifugas-arena-1.jpg\",\"datePublished\":\"2020-04-13T16:19:46+00:00\",\"description\":\"Formigueiro anti-vazamento com areia. Formigueiro para formigas ex\u00f3ticas. Formigueiro de areia. loja de formigueiro acr\u00edlico\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/antderground.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/antifugas-arena-1.jpg\",\"contentUrl\":\"https:\\\/\\\/antderground.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/antifugas-arena-1.jpg\",\"width\":591,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/produto\\\/formigueiro-anti-vazamento-areia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/loja-de-formigueiros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Formigueiro anti-vazamento (areia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/\",\"name\":\"ANTDERGROUND\",\"description\":\"Tu tienda de hormigas, gran variedad de hormigueros acr\u00edlicos,madera,arena,3D y mas.. Pide tus hormigas gratis con tu pedido, somos expertos en hormigueros antifugas.\",\"publisher\":{\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/0e322c505e84fe72c65e2f6d08f96b81\"},\"alternateName\":\"Antderground\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/antderground.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/0e322c505e84fe72c65e2f6d08f96b81\",\"name\":\"Eric de Antderground\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g\",\"caption\":\"Eric de Antderground\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g\"},\"description\":\"Eric es el especialista y fundador de Antderground, con una amplia trayectoria en artr\u00f3podos y enfocado en la mirmecolog\u00eda y el dise\u00f1o de hormigueros artificiales. Su enfoque combina la innovaci\u00f3n t\u00e9cnica con el respeto por la biolog\u00eda de las hormigas, is\u00f3podos y otros, desarrollando sistemas de nidos modulares 3D y acr\u00edlicos que son referentes para aficionados y profesionales en toda Europa. Su objetivo es facilitar la cr\u00eda de hormigas y otros artr\u00f3podos mediante soluciones seguras y divulgaci\u00f3n de calidad.\",\"sameAs\":[\"https:\\\/\\\/antderground.com\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCio72z7TlbufkAthAJIJfPw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formigueiro anti-vazamento (areia) - ANTDERGROUND","description":"Formigueiro anti-vazamento com areia. Formigueiro para formigas ex\u00f3ticas. Formigueiro de areia. loja de formigueiro acr\u00edlico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/","og_locale":"pt_BR","og_type":"article","og_title":"Formigueiro anti-vazamento (areia) - ANTDERGROUND","og_description":"Formigueiro anti-vazamento com areia. Formigueiro para formigas ex\u00f3ticas. Formigueiro de areia. loja de formigueiro acr\u00edlico","og_url":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/","og_site_name":"ANTDERGROUND","og_image":[{"width":591,"height":601,"url":"https:\/\/antderground.com\/wp-content\/uploads\/2020\/04\/antifugas-arena-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/","url":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/","name":"Formigueiro anti-vazamento (areia) - ANTDERGROUND","isPartOf":{"@id":"https:\/\/antderground.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/#primaryimage"},"image":{"@id":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/#primaryimage"},"thumbnailUrl":"https:\/\/antderground.com\/wp-content\/uploads\/2020\/04\/antifugas-arena-1.jpg","datePublished":"2020-04-13T16:19:46+00:00","description":"Formigueiro anti-vazamento com areia. Formigueiro para formigas ex\u00f3ticas. Formigueiro de areia. loja de formigueiro acr\u00edlico","breadcrumb":{"@id":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/#primaryimage","url":"https:\/\/antderground.com\/wp-content\/uploads\/2020\/04\/antifugas-arena-1.jpg","contentUrl":"https:\/\/antderground.com\/wp-content\/uploads\/2020\/04\/antifugas-arena-1.jpg","width":591,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/antderground.com\/pt-br\/produto\/formigueiro-anti-vazamento-areia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/antderground.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/antderground.com\/pt-br\/loja-de-formigueiros\/"},{"@type":"ListItem","position":3,"name":"Formigueiro anti-vazamento (areia)"}]},{"@type":"WebSite","@id":"https:\/\/antderground.com\/pt-br\/#website","url":"https:\/\/antderground.com\/pt-br\/","name":"ANTDERGROUND","description":"Tu tienda de hormigas, gran variedad de hormigueros acr\u00edlicos,madera,arena,3D y mas.. Pide tus hormigas gratis con tu pedido, somos expertos en hormigueros antifugas.","publisher":{"@id":"https:\/\/antderground.com\/pt-br\/#\/schema\/person\/0e322c505e84fe72c65e2f6d08f96b81"},"alternateName":"Antderground","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/antderground.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/antderground.com\/pt-br\/#\/schema\/person\/0e322c505e84fe72c65e2f6d08f96b81","name":"Eric de Antderground","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g","caption":"Eric de Antderground"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/c49a1b9f79216d1498cb73c1e85cd47f4465dda35f2a94c03790d491bd4423c3?s=96&d=mm&r=g"},"description":"Eric es el especialista y fundador de Antderground, con una amplia trayectoria en artr\u00f3podos y enfocado en la mirmecolog\u00eda y el dise\u00f1o de hormigueros artificiales. Su enfoque combina la innovaci\u00f3n t\u00e9cnica con el respeto por la biolog\u00eda de las hormigas, is\u00f3podos y otros, desarrollando sistemas de nidos modulares 3D y acr\u00edlicos que son referentes para aficionados y profesionales en toda Europa. Su objetivo es facilitar la cr\u00eda de hormigas y otros artr\u00f3podos mediante soluciones seguras y divulgaci\u00f3n de calidad.","sameAs":["https:\/\/antderground.com\/","https:\/\/www.youtube.com\/channel\/UCio72z7TlbufkAthAJIJfPw"]}]}},"_links":{"self":[{"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/product\/19348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/product\/19348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/media\/19362"}],"wp:attachment":[{"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/media?parent=19348"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/product_brand?post=19348"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/product_cat?post=19348"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/antderground.com\/pt-br\/wp-json\/wp\/v2\/product_tag?post=19348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}